{"id":15439,"date":"2023-11-08T13:39:02","date_gmt":"2023-11-08T16:39:02","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/?p=15439"},"modified":"2023-11-23T13:42:34","modified_gmt":"2023-11-23T16:42:34","slug":"programacao-de-cursos-para-novembro","status":"publish","type":"post","link":"https:\/\/sejuri.sc.gov.br\/en\/programacao-de-cursos-para-novembro\/","title":{"rendered":"Programa\u00e7\u00e3o de cursos para novembro"},"content":{"rendered":"<p>A Academia de Administra\u00e7\u00e3o Prisional e Socioeducativa (ACAPS) tem o prazer de anunciar sua agenda de cursos para o m\u00eas de novembro, estes cursos atendem tanto a Forma\u00e7\u00e3o Profissional quanto a Forma\u00e7\u00e3o Continuada. Com um compromisso cont\u00ednuo com a excel\u00eancia em educa\u00e7\u00e3o e treinamento, a ACAPS oferece uma s\u00e9rie de cursos projetados para equipar profissionais com as habilidades e conhecimentos necess\u00e1rios para enfrentar os desafios din\u00e2micos dos ambientes prisional e socioeducativo.<\/p>\n<p>A ACAPS se dedica a oferecer treinamento de qualidade que n\u00e3o apenas atenda \u00e0s necessidades atuais dos profissionais da \u00e1rea, mas tamb\u00e9m os prepare para as inova\u00e7\u00f5es e desafios futuros. Junte-se a n\u00f3s para desenvolver suas habilidades e contribuir para a melhoria do sistema prisional e socioeducativo.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-15440 size-full\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2023\/11\/Cursos_Acaps_Novembro_2-1.jpg\" alt=\"\" width=\"604\" height=\"510\" srcset=\"https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2023\/11\/Cursos_Acaps_Novembro_2-1.jpg 604w, https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2023\/11\/Cursos_Acaps_Novembro_2-1-300x253.jpg 300w\" sizes=\"(max-width: 604px) 100vw, 604px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>A Academia de Administra\u00e7\u00e3o Prisional e Socioeducativa (ACAPS) tem o prazer de anunciar sua agenda de cursos para o m\u00eas de novembro, estes cursos atendem tanto a Forma\u00e7\u00e3o Profissional quanto a Forma\u00e7\u00e3o Continuada. Com um compromisso cont\u00ednuo com a excel\u00eancia em educa\u00e7\u00e3o e treinamento, a ACAPS oferece uma s\u00e9rie de cursos projetados para equipar profissionais [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":15441,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1315],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:42:49","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/15439"}],"collection":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=15439"}],"version-history":[{"count":0,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/15439\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/15441"}],"wp:attachment":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=15439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=15439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=15439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}