{"id":15826,"date":"2023-09-25T15:23:58","date_gmt":"2023-09-25T18:23:58","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/?p=15826"},"modified":"2023-12-13T15:26:00","modified_gmt":"2023-12-13T18:26:00","slug":"doacao-de-alimento-do-case-de-chapeco-a-comunidade-promove-fortalecimento-de-vinculos-sociais","status":"publish","type":"post","link":"https:\/\/sejuri.sc.gov.br\/en\/doacao-de-alimento-do-case-de-chapeco-a-comunidade-promove-fortalecimento-de-vinculos-sociais\/","title":{"rendered":"Doa\u00e7\u00e3o de alimento do CASE de Chapec\u00f3 \u00e0 comunidade promove fortalecimento de v\u00ednculos sociais"},"content":{"rendered":"<p>A dire\u00e7\u00e3o do CASE de Chapec\u00f3 demonstrou um comprometimento louv\u00e1vel com a comunidade local ao realizar a doa\u00e7\u00e3o de 15 kg de til\u00e1pias por meio das atividades do Servi\u00e7o de Conviv\u00eancia e Fortalecimento de V\u00ednculos (SCFV). Essa doa\u00e7\u00e3o, realizada com a parceria da Prefeitura de Chapec\u00f3 e a ONG Programa Viver, ir\u00e1 atender aproximadamente 80 crian\u00e7as e adolescentes de 6 a 15 anos em situa\u00e7\u00e3o de vulnerabilidade social no bairro Quedas do Palmital, em Chapec\u00f3.<\/p>\n<p>Os peixes s\u00e3o criados para doa\u00e7\u00e3o nas instala\u00e7\u00f5es do Centro de Atendimento Socioeducativo (CASE) e simboliza o compromisso em promover o fortalecimento de v\u00ednculos sociais entre esses jovens. O Servi\u00e7o de Conviv\u00eancia e Fortalecimento de V\u00ednculos, programa do Governo Federal, oferece \u00e0queles que enfrentam vulnerabilidades sociais a oportunidade de refletir sobre sua realidade, contribuindo para o planejamento de estrat\u00e9gias e a constru\u00e7\u00e3o de novos projetos de vida.<\/p>\n<p>O diretor do CASE de Chapec\u00f3, Valdecir Francisco Cortina, enfatizou que essa a\u00e7\u00e3o vai al\u00e9m da simples doa\u00e7\u00e3o de alimentos, pois fortalece os la\u00e7os comunit\u00e1rios, proporcionando oportunidades para que as crian\u00e7as e adolescentes se sintam parte integrante da sociedade e tenham acesso a recursos que possam melhorar suas vidas.<\/p>\n<p>\u201cEssa iniciativa n\u00e3o apenas beneficia a comunidade local, mas tamb\u00e9m fortalece os v\u00ednculos dos 49 adolescentes atualmente internados no CASE com a sociedade. Atrav\u00e9s de a\u00e7\u00f5es como essa criam um ambiente mais inclusivo e igualit\u00e1rio para todos os seus membros\u201d, destacou o diretor.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-large wp-image-15827\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2023\/12\/CASEchapeco1-1024x576.jpg\" alt=\"\" width=\"696\" height=\"392\" srcset=\"https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2023\/12\/CASEchapeco1-1024x576.jpg 1024w, https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2023\/12\/CASEchapeco1-300x169.jpg 300w, https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2023\/12\/CASEchapeco1-768x432.jpg 768w, https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2023\/12\/CASEchapeco1-1536x864.jpg 1536w, https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2023\/12\/CASEchapeco1.jpg 1600w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/p>\n<p>Al\u00e9m desse programa, s\u00e3o oferecidas aos adolescentes do CASE de Chapec\u00f3 diversos programas, como oficinas esportivas, m\u00fasica, inform\u00e1tica, xadrez, panifica\u00e7\u00e3o, al\u00e9m de projetos de incentivo \u00e0 leitura e escrita. Entre as atividades realizadas pelos adolescentes est\u00e1 a revitaliza\u00e7\u00e3o e pintura, agricultura, piscicultura, entre outras atividades de car\u00e1ter profissionalizante oferecidos aos internos.<\/p>\n<p>O diretor Valdecir Francisco Cortina tamb\u00e9m mencionou que houve contato com o CIEE (Centro de Integra\u00e7\u00e3o Empresa-Escola) no m\u00eas anterior para a realiza\u00e7\u00e3o de oficinas e, possivelmente, cursos futuros para o desenvolvimento de atividades externas ao CASE, com o apoio do Poder Judici\u00e1rio e do Setor\u00a0de\u00a0Seguran\u00e7a.<\/p>","protected":false},"excerpt":{"rendered":"<p>A dire\u00e7\u00e3o do CASE de Chapec\u00f3 demonstrou um comprometimento louv\u00e1vel com a comunidade local ao realizar a doa\u00e7\u00e3o de 15 kg de til\u00e1pias por meio das atividades do Servi\u00e7o de Conviv\u00eancia e Fortalecimento de V\u00ednculos (SCFV). Essa doa\u00e7\u00e3o, realizada com a parceria da Prefeitura de Chapec\u00f3 e a ONG Programa Viver, ir\u00e1 atender aproximadamente 80 [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":15828,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79,46],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:02:39","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/15826"}],"collection":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=15826"}],"version-history":[{"count":0,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/15826\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/15828"}],"wp:attachment":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=15826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=15826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=15826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}