{"id":15837,"date":"2023-09-21T15:30:09","date_gmt":"2023-09-21T18:30:09","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/?p=15837"},"modified":"2023-12-13T15:31:15","modified_gmt":"2023-12-13T18:31:15","slug":"curso-do-pronatec-e-oferecido-ao-publico-lgbtqi-na-penitenciaria-de-florianopolis","status":"publish","type":"post","link":"https:\/\/sejuri.sc.gov.br\/en\/curso-do-pronatec-e-oferecido-ao-publico-lgbtqi-na-penitenciaria-de-florianopolis\/","title":{"rendered":"Curso do Pronatec \u00e9 oferecido ao p\u00fablico LGBTQI+ na Penitenci\u00e1ria de Florian\u00f3polis"},"content":{"rendered":"<p>Na busca por ampliar a oferta de cursos de forma\u00e7\u00e3o profissional, bem como facilitar o acesso \u00e0 educa\u00e7\u00e3o para a popula\u00e7\u00e3o privada de liberdade, a Penitenci\u00e1ria de Florian\u00f3polis implementou na unidade o curso de Assistente Administrativo. A a\u00e7\u00e3o \u00e9 realizada por meio do Programa Nacional de Acesso ao Ensino T\u00e9cnico e Emprego (Pronatec) e se destina primeiramente \u00e0 comunidade LGBTQI+ que se encontra sob cust\u00f3dia. Em breve, outro curso, este em parceria com a OAB, tamb\u00e9m ser\u00e1 oferecido a esse p\u00fablico na unidade prisional.<\/p>\n<p>As aulas abordam t\u00f3picos relacionados ao gerenciamento administrativo, empreendedorismo, marketing, contabilidade e sistemas de informa\u00e7\u00e3o. Elas s\u00e3o ministradas na sala de inform\u00e1tica da institui\u00e7\u00e3o prisional, que foi doada pelo Conselho da Comunidade em parceria com a Vara de Execu\u00e7\u00f5es Penais da Comarca da Capital de Florian\u00f3polis.<\/p>\n<p>O diretor da unidade, Max Orth, destacou que esse projeto visa proporcionar forma\u00e7\u00e3o profissional para os indiv\u00edduos LGBTQI+ com o objetivo de integr\u00e1-los ao mercado de trabalho. \u201cIsso n\u00e3o apenas oferece oportunidades de ressocializa\u00e7\u00e3o, mas tamb\u00e9m contribui para a redu\u00e7\u00e3o da reincid\u00eancia criminal. Al\u00e9m disso, os participantes que demonstram bom desempenho no curso recebem um Certificado do Centro de Educa\u00e7\u00e3o Profissional e podem receber uma premia\u00e7\u00e3o de 420 reais por boa frequ\u00eancia nas aulas\u201d, destacou.<\/p>\n<p>Tamb\u00e9m s\u00e3o oferecidos \u00e0 popula\u00e7\u00e3o LGBTQI+ outros programas educacionais, como os Centros de Educa\u00e7\u00e3o de Jovens e Adultos, o Projeto Despertar pela Leitura e o Exame Nacional para Certifica\u00e7\u00e3o de Compet\u00eancias de Jovens e Adultos, que visam promover o desenvolvimento educacional e profissional dos apenados, bem como a possibilidade de remiss\u00e3o de suas penas.<\/p>\n<p>Al\u00e9m disso, a Academia de Administra\u00e7\u00e3o Prisional e Socioeducativa est\u00e1 realizando desde agosto o Curso de Capacita\u00e7\u00e3o aos Policiais Penais e tamb\u00e9m aos demais servidores administrativos relacionado ao tratamento e atendimento \u00e0 popula\u00e7\u00e3o LGBTQIA+. O objetivo \u00e9 garantir que a cust\u00f3dia dessa popula\u00e7\u00e3o seja garantida em conformidade aos seus direitos.<\/p>\n<p>\u201cEssas a\u00e7\u00f5es, entre outras que realizamos, demonstram o compromisso em promover uma presta\u00e7\u00e3o de servi\u00e7os mais eficiente e garantindo o respeito amplo \u00e0s especificidades desse grupo no sistema prisional e a prote\u00e7\u00e3o de seus direitos. Desta forma, tamb\u00e9m resguardamos os pr\u00f3prios policiais penais, que sendo capacitados ter\u00e3o suas a\u00e7\u00f5es pautadas no regramento legal vigente e nos padr\u00f5es estabelecidos pelo CNJ\u201d, frisou a secret\u00e1ria adjunta da SAP, Joana\u00a0Mahfuz\u00a0Vicini.<\/p>","protected":false},"excerpt":{"rendered":"<p>Na busca por ampliar a oferta de cursos de forma\u00e7\u00e3o profissional, bem como facilitar o acesso \u00e0 educa\u00e7\u00e3o para a popula\u00e7\u00e3o privada de liberdade, a Penitenci\u00e1ria de Florian\u00f3polis implementou na unidade o curso de Assistente Administrativo. A a\u00e7\u00e3o \u00e9 realizada por meio do Programa Nacional de Acesso ao Ensino T\u00e9cnico e Emprego (Pronatec) e se [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":15838,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296,46],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 13:23:23","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/15837"}],"collection":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=15837"}],"version-history":[{"count":0,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/15837\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/15838"}],"wp:attachment":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=15837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=15837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=15837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}