{"id":17429,"date":"2024-01-23T17:09:35","date_gmt":"2024-01-23T20:09:35","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/?p=17429"},"modified":"2024-02-14T17:12:16","modified_gmt":"2024-02-14T20:12:16","slug":"governador-entrega-nova-identidade-funcional-de-policiais-penais-em-reuniao-com-superintendentes-e-diretores-da-sap","status":"publish","type":"post","link":"https:\/\/sejuri.sc.gov.br\/en\/governador-entrega-nova-identidade-funcional-de-policiais-penais-em-reuniao-com-superintendentes-e-diretores-da-sap\/","title":{"rendered":"Governador entrega nova identidade funcional de policiais penais em reuni\u00e3o com superintendentes e diretores da SAP"},"content":{"rendered":"<p>O governador Jorginho Mello fez uma participa\u00e7\u00e3o surpresa em um evento da Secretaria de Administra\u00e7\u00e3o Prisional e Socioeducativa (SAP) realizado na Capital de Santa Catarina. Na manh\u00e3 desta ter\u00e7a, 23, come\u00e7ou a reuni\u00e3o de superintendentes e diretores de pres\u00eddios da regional da Grande Florian\u00f3polis e vai at\u00e9 esta quarta, 24. O governador entregou as novas carteiras funcionais de policiais penais presentes no evento.<\/p>\n<p>\u201c\u00c9 muito bom ver nossos servidores trabalhando em conjunto pra fazermos um ano de 2024 ainda melhor do que o ano passado. Espero ver aqui muitos projetos que coloquem os presos pra trabalhar, para que aprendam e tenham uma profiss\u00e3o quando terminarem de cumprir o que devem pra sociedade\u201d, disse o governador Jorginho Mello.<\/p>\n<p>O encontro \u00e9 o primeiro de uma s\u00e9rie de oito reuni\u00f5es com todos os superintendentes e diretores de unidades prisionais. A proposta \u00e9 realizar de forma regionalizada um diagn\u00f3stico sobre o ano de 2023 e trabalhar no planejamento dos projetos que ser\u00e3o executados neste ano. No encontro da Grande Florian\u00f3polis, o evento foi realizado na sala de cinema do CIC.<\/p>\n<p>\u201cAgradecemos a presen\u00e7a do governador aqui neste evento de entrega das identidades funcionais aos policiais penais, uma reinvindica\u00e7\u00e3o muito antiga da categoria. A reuni\u00e3o de hoje tamb\u00e9m \u00e9 importante para o alinhamento e planejamento das novas metas do Governo do Estado para o sistema prisional catarinense\u201d, disse o secret\u00e1rio\u00a0Carlos\u00a0Alves.<\/p>\n<p>Ainda nesta ter\u00e7a-feira, os policiais penais far\u00e3o uma visita t\u00e9cnica ao complexo prisional da Capital. J\u00e1 a quarta-feira tem o dia reservado para a realiza\u00e7\u00e3o dessas agendas externas. Ser\u00e3o visitadas as unidades de Tijucas, Bigua\u00e7u, S\u00e3o Pedro de Alc\u00e2ntara e Palho\u00e7a ao\u00a0longo\u00a0do\u00a0dia.<\/p>","protected":false},"excerpt":{"rendered":"<p>O governador Jorginho Mello fez uma participa\u00e7\u00e3o surpresa em um evento da Secretaria de Administra\u00e7\u00e3o Prisional e Socioeducativa (SAP) realizado na Capital de Santa Catarina. Na manh\u00e3 desta ter\u00e7a, 23, come\u00e7ou a reuni\u00e3o de superintendentes e diretores de pres\u00eddios da regional da Grande Florian\u00f3polis e vai at\u00e9 esta quarta, 24. O governador entregou as novas [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":17430,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296,46],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:33:00","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/17429"}],"collection":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=17429"}],"version-history":[{"count":0,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/17429\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/17430"}],"wp:attachment":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=17429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=17429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=17429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}