{"id":20425,"date":"2025-02-07T10:21:51","date_gmt":"2025-02-07T13:21:51","guid":{"rendered":"https:\/\/www.sap.sc.gov.br\/?p=20425"},"modified":"2025-02-07T10:27:15","modified_gmt":"2025-02-07T13:27:15","slug":"governo-do-estado-celebra-parceria-laboral-entre-a-sejuri-e-a-industria-de-confeccoes-ogochi","status":"publish","type":"post","link":"https:\/\/sejuri.sc.gov.br\/en\/governo-do-estado-celebra-parceria-laboral-entre-a-sejuri-e-a-industria-de-confeccoes-ogochi\/","title":{"rendered":"Governo do Estado celebra Parceria Laboral entre a SEJURI e a ind\u00fastria de confec\u00e7\u00f5es Ogochi"},"content":{"rendered":"<p>Nesta \u00faltima quinta-feira (06), em um evento na Penitenci\u00e1ria Regional de Curitibanos, o Governo Estado, atrav\u00e9s da Secretaria de Estado de Justi\u00e7a e Reintegra\u00e7\u00e3o Social, celebrou a Parceria Laboral com a ind\u00fastria de confec\u00e7\u00f5es Ogochi.<\/p>\n<p>Em Curitibanos, a empresa possui uma \u00e1rea de 1077m\u00b2, que oferece 150 vagas de trabalho. Na unidade de S\u00e3o Crist\u00f3v\u00e3o, s\u00e3o duas \u00e1reas de 600m\u00b2, com previs\u00e3o de 300 internos trabalhando ao t\u00e9rmino da obra.<br \/>\n<a href=\"http:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2025\/02\/IMG-20250206-WA0025-copiar-scaled.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-large wp-image-20429\" src=\"http:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2025\/02\/IMG-20250206-WA0025-copiar-1024x630.jpg\" alt=\"\" width=\"696\" height=\"428\" srcset=\"https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/02\/IMG-20250206-WA0025-copiar-1024x630.jpg 1024w, https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/02\/IMG-20250206-WA0025-copiar-300x185.jpg 300w, https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/02\/IMG-20250206-WA0025-copiar-768x473.jpg 768w, https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/02\/IMG-20250206-WA0025-copiar-1536x945.jpg 1536w, https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/02\/IMG-20250206-WA0025-copiar-2048x1260.jpg 2048w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/a><\/p>\n<p>A empresa Ogochi possui 5 termos de Parceria Laboral assinados com a SEJURI. Os internos trabalham nas penitenci\u00e1rias de Itaja\u00ed, de S\u00e3o Crist\u00f3v\u00e3o com Sul, Agr\u00edcola de Chapec\u00f3, de Crici\u00fama e da Regi\u00e3o de Curitibanos. A empresa \u00e9 destaque no pa\u00eds em n\u00famero de vagas disponibilizadas.<\/p>\n<p>O secret\u00e1rio da SEJURI Carlos Alves ressaltou o trabalho realizado pelos policiais penais. \u201cMuito importante essas parcerias, agradecemos aos empres\u00e1rios por acreditarem em nosso sistema prisional. Os prefeitos tamb\u00e9m, por aceitarem muitas vezes uma unidade prisional, mas eu n\u00e3o posso deixar de lembrar e fazer minha refer\u00eancia aos policiais penais. Esses s\u00e3o os verdadeiros her\u00f3is da cena, do nosso sistema que \u00e9 refer\u00eancia\u201d.<\/p>\n<p><a href=\"http:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2025\/02\/SOLENIDADE-PENITENCIARIA-OGOCHI-21-1-scaled.jpg\"><img decoding=\"async\" class=\"aligncenter size-large wp-image-20430\" src=\"http:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2025\/02\/SOLENIDADE-PENITENCIARIA-OGOCHI-21-1-1024x683.jpg\" alt=\"\" width=\"696\" height=\"464\" srcset=\"https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/02\/SOLENIDADE-PENITENCIARIA-OGOCHI-21-1-1024x683.jpg 1024w, https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/02\/SOLENIDADE-PENITENCIARIA-OGOCHI-21-1-300x200.jpg 300w, https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/02\/SOLENIDADE-PENITENCIARIA-OGOCHI-21-1-768x512.jpg 768w, https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/02\/SOLENIDADE-PENITENCIARIA-OGOCHI-21-1-1536x1024.jpg 1536w, https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/02\/SOLENIDADE-PENITENCIARIA-OGOCHI-21-1-2048x1365.jpg 2048w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/a><\/p>\n<p>Com mais de tr\u00eas d\u00e9cadas de trajet\u00f3ria no Brasil, com foco no mercado de moda masculina, a Ogochi conta com unidades em 10 munic\u00edpios de Santa Catarina, com mais de 50mil m\u00b2 de \u00e1rea constru\u00edda e capacidade produtiva de mais de 80mil pe\u00e7as por dia.<\/p>\n<p>Santa Catarina tem 8.642 detentos em alguma atividade laboral. O n\u00famero representa aproximadamente 32% da popula\u00e7\u00e3o privada de liberdade, n\u00famero acima da m\u00e9dia nacional, que \u00e9 de 19%. Os dados t\u00eam o Estado como destaque nacional. Avan\u00e7amos de uma m\u00e9dia de 6500 presos trabalhando em 2023 para uma m\u00e9dia de quase 7500 presos no final de 2024.<\/p>\n<p>\u201cHoje, com o apoio dos empres\u00e1rios que apoiam esses projetos e se comprometem a fazer grandes investimentos no sistema prisional, n\u00f3s estamos conseguindo evoluir bastante. N\u00f3s temos, al\u00e9m dos mais de 180 conv\u00eanios assinados, 55 parcerias com prefeituras de Santa Catarina, onde mais de 550 internos trabalham nas cidades. E essa ferramenta, al\u00e9m de beneficiar o sistema, tamb\u00e9m vai trazer um resultado para a vida da pessoa que est\u00e1 privada da liberdade\u201d destacou o diretor-geral da Pol\u00edcia Penal, Roberval D\u2019\u00c1vila Ferraz.<\/p>\n<p>Fotos cr\u00e9ditos: Jaison Lopes<\/p>","protected":false},"excerpt":{"rendered":"<p>Nesta \u00faltima quinta-feira (06), em um evento na Penitenci\u00e1ria Regional de Curitibanos, o Governo Estado, atrav\u00e9s da Secretaria de Estado de Justi\u00e7a e Reintegra\u00e7\u00e3o Social, celebrou a Parceria Laboral com a ind\u00fastria de confec\u00e7\u00f5es Ogochi. Em Curitibanos, a empresa possui uma \u00e1rea de 1077m\u00b2, que oferece 150 vagas de trabalho. Na unidade de S\u00e3o Crist\u00f3v\u00e3o, [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":20427,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296,46],"tags":[1336],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 22:06:23","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/20425"}],"collection":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=20425"}],"version-history":[{"count":0,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/20425\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/20427"}],"wp:attachment":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=20425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=20425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=20425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}