{"id":20930,"date":"2025-04-25T18:02:36","date_gmt":"2025-04-25T21:02:36","guid":{"rendered":"https:\/\/www.sap.sc.gov.br\/?p=20930"},"modified":"2025-04-25T18:05:38","modified_gmt":"2025-04-25T21:05:38","slug":"inauguracao-do-centro-de-treinamento-operacional-regional-norte","status":"publish","type":"post","link":"https:\/\/sejuri.sc.gov.br\/en\/inauguracao-do-centro-de-treinamento-operacional-regional-norte\/","title":{"rendered":"Inaugura\u00e7\u00e3o do Centro de Treinamento Operacional Regional Norte"},"content":{"rendered":"<p>Inaugurado nesta sexta-feira (25), o Centro de Treinamento Operacional Regional Norte, localizado no Complexo Penitenci\u00e1rio de Joinville. O novo espa\u00e7o, que abriga um moderno estande de tiro fechado, foi idealizado pelos Policiais Penais Cristiano Castoldi e Larissa Raquel Cerdeira e representa um importante avan\u00e7o na capacita\u00e7\u00e3o t\u00e9cnica e t\u00e1tica dos profissionais do sistema penitenci\u00e1rio em Santa Catarina.<\/p>\n<p>A cerim\u00f4nia de inaugura\u00e7\u00e3o contou com a presen\u00e7a da Secret\u00e1ria de Justi\u00e7a e Reintegra\u00e7\u00e3o Social, que destacou a import\u00e2ncia do investimento em infraestrutura e forma\u00e7\u00e3o continuada dos Policiais Penais. \u201cEssa entrega representa mais do que um espa\u00e7o f\u00edsico. \u00c9 um compromisso com a valoriza\u00e7\u00e3o dos nossos servidores e com a seguran\u00e7a de toda a sociedade catarinense\u201d, afirmou.<br \/>\nA ideia do estande de tiro come\u00e7ou a ser desenhada em 2022, com o objetivo de criar um ambiente seguro e adequado para o treinamento dos Policiais Penais da SEJURI e para a realiza\u00e7\u00e3o de cursos ministrados pela Academia de Administra\u00e7\u00e3o Prisional e Socioeducativa. A estrutura, com 250 m\u00b2 de \u00e1rea constru\u00edda, foi planejada com foco na funcionalidade e seguran\u00e7a, utilizando concreto armado, alvenaria de blocos, cobertura de eucalipto tratado e telhas de fibrocimento. O interior conta com isolamento ac\u00fastico, para-balas de pneus e escoras de madeira, al\u00e9m de chapas met\u00e1licas nas paredes e teto para evitar ricochetes.<\/p>\n<p><a href=\"http:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2025\/04\/VID-20250425-WA0044_Moment.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-20934 size-full\" src=\"http:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2025\/04\/VID-20250425-WA0044_Moment.jpg\" alt=\"\" width=\"900\" height=\"720\" srcset=\"https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/04\/VID-20250425-WA0044_Moment.jpg 900w, https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/04\/VID-20250425-WA0044_Moment-300x240.jpg 300w, https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/04\/VID-20250425-WA0044_Moment-768x614.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p>O projeto foi desenvolvido pela Policial Penal e Engenheira Civil Larissa Raquel Cerdeira, que incorporou t\u00e9cnicas espec\u00edficas de tiro ao desenho arquitet\u00f4nico, contando com o apoio e conhecimento de diversos colegas da corpora\u00e7\u00e3o.<br \/>\nMais de 220 Policiais Penais das unidades de Joinville, S\u00e3o Francisco do Sul e Barra Velha ser\u00e3o beneficiados diretamente, al\u00e9m de agentes de outras regi\u00f5es do Estado que poder\u00e3o utilizar o espa\u00e7o. A obra foi viabilizada por meio de uma parceria entre a SEJURI, a Associa\u00e7\u00e3o dos Policiais Penais e Agentes de Seguran\u00e7a Socioeducativos (APPS) e a Superintend\u00eancia Regional Norte (SR03), com recursos financeiros repassados pela Justi\u00e7a Federal de Joinville \u00e0 APPS e complementados pelo Fundo Rotativo Regional Norte e pela pr\u00f3pria SEJURI.<br \/>\nA constru\u00e7\u00e3o contou com o trabalho de internos da Penitenci\u00e1ria Industrial de Joinville, refor\u00e7ando o compromisso com a ressocializa\u00e7\u00e3o por meio do trabalho.<\/p>\n<p><a href=\"http:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2025\/04\/IMG-20250425-WA0091.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-20935 size-large\" src=\"http:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2025\/04\/IMG-20250425-WA0091-768x1024.jpg\" alt=\"\" width=\"696\" height=\"928\" srcset=\"https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/04\/IMG-20250425-WA0091-768x1024.jpg 768w, https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/04\/IMG-20250425-WA0091-225x300.jpg 225w, https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/04\/IMG-20250425-WA0091.jpg 1066w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/a><\/p>\n<p>O Superintendente Regional Norte, Efraym, e o Diretor da Penitenci\u00e1ria Industrial de Joinville, Carlos Rossato, foram citados como pe\u00e7as-chave na concretiza\u00e7\u00e3o do projeto. \u201cA dedica\u00e7\u00e3o e o envolvimento direto dos Policiais Penais foram fundamentais para que hoje pud\u00e9ssemos entregar esse espa\u00e7o de excel\u00eancia \u00e0 categoria\u201d, destacou Efraym.<br \/>\nCom a entrega do novo estande, os Policiais Penais catarinenses passam a contar com uma estrutura de ponta para treinamentos e capacita\u00e7\u00f5es, fortalecendo a atua\u00e7\u00e3o da seguran\u00e7a p\u00fablica no Estado.<\/p>","protected":false},"excerpt":{"rendered":"<p>Inaugurado nesta sexta-feira (25), o Centro de Treinamento Operacional Regional Norte, localizado no Complexo Penitenci\u00e1rio de Joinville. O novo espa\u00e7o, que abriga um moderno estande de tiro fechado, foi idealizado pelos Policiais Penais Cristiano Castoldi e Larissa Raquel Cerdeira e representa um importante avan\u00e7o na capacita\u00e7\u00e3o t\u00e9cnica e t\u00e1tica dos profissionais do sistema penitenci\u00e1rio em [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":20933,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296,46],"tags":[1336],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 22:54:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/20930"}],"collection":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=20930"}],"version-history":[{"count":0,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/20930\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/20933"}],"wp:attachment":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=20930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=20930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=20930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}