{"id":21312,"date":"2025-06-06T19:04:43","date_gmt":"2025-06-06T22:04:43","guid":{"rendered":"https:\/\/www.sap.sc.gov.br\/?p=21312"},"modified":"2025-06-06T19:22:39","modified_gmt":"2025-06-06T22:22:39","slug":"acaps-forma-26-servidores-especializados-em-inteligencia-penitenciaria","status":"publish","type":"post","link":"https:\/\/sejuri.sc.gov.br\/en\/acaps-forma-26-servidores-especializados-em-inteligencia-penitenciaria\/","title":{"rendered":"ACAPS forma 26 servidores especializados em intelig\u00eancia penitenci\u00e1ria"},"content":{"rendered":"<p><i><span style=\"font-weight: 400;\">Capacita\u00e7\u00e3o promovida pela ACAPS forma 26 servidores especializados em atua\u00e7\u00e3o estrat\u00e9gica no sistema prisional<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0O audit\u00f3rio do Centro Integrado de Cultura (CIC) foi palco, nesta sexta-feira (06), de uma cerim\u00f4nia que celebrou mais do que a conclus\u00e3o de um curso: simbolizou o avan\u00e7o da intelig\u00eancia penitenci\u00e1ria em Santa Catarina. Vinte e seis servidores receberam seus certificados de conclus\u00e3o do Curso de Intelig\u00eancia Penitenci\u00e1ria, promovido pela Academia de Administra\u00e7\u00e3o Prisional e Socioeducativa (ACAPS), com o apoio da Secretaria de Estado de Justi\u00e7a e Reintegra\u00e7\u00e3o Social (SEJURI).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Realizado entre os dias 19 de maio e 5 de junho, o curso teve carga hor\u00e1ria de 152 horas-aula e combinou atividades presenciais e a dist\u00e2ncia. Durante o per\u00edodo, os participantes foram preparados para atuar de forma t\u00e9cnica, \u00e9tica e estrat\u00e9gica no campo da intelig\u00eancia voltada ao sistema penitenci\u00e1rio.<\/span><\/p>\n<figure id=\"attachment_21319\" aria-describedby=\"caption-attachment-21319\" style=\"width: 696px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-06-at-16.20.18-3.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-21319 size-large\" src=\"http:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-06-at-16.20.18-3-1024x702.jpeg\" alt=\"\" width=\"696\" height=\"477\" srcset=\"https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-06-at-16.20.18-3-1024x702.jpeg 1024w, https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-06-at-16.20.18-3-300x206.jpeg 300w, https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-06-at-16.20.18-3-768x526.jpeg 768w, https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-06-at-16.20.18-3-1536x1052.jpeg 1536w, https:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/06\/WhatsApp-Image-2025-06-06-at-16.20.18-3-2048x1403.jpeg 2048w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/a><figcaption id=\"caption-attachment-21319\" class=\"wp-caption-text\">Cr\u00e9dito: Jaqueline Noceti\/SEJURI<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">O conte\u00fado abrangeu temas essenciais, como Direitos Humanos, Contraintelig\u00eancia, Fundamentos Doutrin\u00e1rios, Opera\u00e7\u00f5es de Intelig\u00eancia, Investiga\u00e7\u00e3o Social e An\u00e1lise de Organiza\u00e7\u00f5es Criminosas. Os alunos tamb\u00e9m participaram de m\u00f3dulos pr\u00e1ticos, que inclu\u00edram Saque Velado, Fotografia T\u00e9cnica, Combate Veicular e uso de Sistemas e Equipamentos em laborat\u00f3rio. A proposta do curso, segundo a organiza\u00e7\u00e3o, foi promover a integra\u00e7\u00e3o entre teoria e pr\u00e1tica, elevando o n\u00edvel de prepara\u00e7\u00e3o dos servidores.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cEssa forma\u00e7\u00e3o vai muito al\u00e9m do aperfei\u00e7oamento t\u00e9cnico. Ela reafirma nosso compromisso com uma intelig\u00eancia institucional robusta, respeitosa aos direitos fundamentais e alinhada aos princ\u00edpios da legalidade e da efici\u00eancia\u201d, afirmou, o secret\u00e1rio adjunto de Estado de Justi\u00e7a e Reintegra\u00e7\u00e3o Social, Leandro Lisboa Ferreira de Melo, que esteve presente no evento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A cerim\u00f4nia reuniu tamb\u00e9m autoridades do setor, como o diretor da ACAPS, Marcelo Coelho Souza; o diretor-geral da Pol\u00edcia Penal de Santa Catarina, Maicon Ronald Alves; e o diretor de Intelig\u00eancia e Informa\u00e7\u00e3o da SEJURI, Marcelo Forbici.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em nome da ACAPS, Marcelo Souza destacou o empenho dos formandos: \u201cEsses servidores assumem, a partir de hoje, uma nova responsabilidade diante do sistema penitenci\u00e1rio. Est\u00e3o aptos a atuar com intelig\u00eancia e discernimento, sendo pe\u00e7as-chave no fortalecimento da nossa seguran\u00e7a institucional.\u201d<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O curso integra a pol\u00edtica de capacita\u00e7\u00e3o continuada da SEJURI e refor\u00e7a a estrat\u00e9gia do Estado de formar quadros t\u00e9cnicos especializados para enfrentar os desafios complexos da seguran\u00e7a prisional, incluindo o monitoramento e a desarticula\u00e7\u00e3o de organiza\u00e7\u00f5es criminosas que atuam dentro e fora das unidades prisionais.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A forma\u00e7\u00e3o encerrada hoje representa um marco importante no aprimoramento da pol\u00edtica de intelig\u00eancia penitenci\u00e1ria em Santa Catarina \u2014 um campo cada vez mais estrat\u00e9gico e vital para a preserva\u00e7\u00e3o da ordem, da seguran\u00e7a e da justi\u00e7a no sistema prisional.<\/span><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Capacita\u00e7\u00e3o promovida pela ACAPS forma 26 servidores especializados em atua\u00e7\u00e3o estrat\u00e9gica no sistema prisional \u00a0O audit\u00f3rio do Centro Integrado de Cultura (CIC) foi palco, nesta sexta-feira (06), de uma cerim\u00f4nia que celebrou mais do que a conclus\u00e3o de um curso: simbolizou o avan\u00e7o da intelig\u00eancia penitenci\u00e1ria em Santa Catarina. Vinte e seis servidores receberam seus [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":21313,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1315,1296,46],"tags":[1336],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 21:56:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/21312"}],"collection":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=21312"}],"version-history":[{"count":0,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/21312\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/21313"}],"wp:attachment":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=21312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=21312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=21312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}