{"id":2569,"date":"2013-08-02T16:44:44","date_gmt":"2013-08-02T16:44:44","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2013\/08\/02\/cancelamento-de-capacitacao\/"},"modified":"2013-08-02T16:44:44","modified_gmt":"2013-08-02T16:44:44","slug":"cancelamento-de-capacitacao","status":"publish","type":"post","link":"https:\/\/sejuri.sc.gov.br\/en\/cancelamento-de-capacitacao\/","title":{"rendered":"Cancelamento de capacita\u00e7\u00e3o"},"content":{"rendered":"<p>Informamos aos servidores contratados para atuar junto ao Centro de Atendimento Socioeducativo (CASE) de Joinville que a capacita\u00e7\u00e3o agendada inicialmente para o dia 06\/08\/2013 foi CANCELADA.<\/p>\n<p>T\u00e3o logo tenhamos nova data para o in\u00edcio do processo de capacita\u00e7\u00e3o para o corpo tecnico (n\u00edvel m\u00e9dio e superior), instrutores e agentes socioeducativos publicaremos informa\u00e7\u00f5es no site do DEASE.&nbsp;<\/p>\n<p>Em caso de d\u00favida entrar em contato com o DEASE por meio do telefone (48) 2107 2974 ou do e-mail gabinete@dease.sc.gov.br .<\/p>","protected":false},"excerpt":{"rendered":"<p>Informamos aos servidores contratados para atuar junto ao Centro de Atendimento Socioeducativo (CASE) de Joinville que a capacita\u00e7\u00e3o agendada inicialmente para o dia 06\/08\/2013 foi CANCELADA. T\u00e3o logo tenhamos nova data para o in\u00edcio do processo de capacita\u00e7\u00e3o para o corpo tecnico (n\u00edvel m\u00e9dio e superior), instrutores e agentes socioeducativos publicaremos informa\u00e7\u00f5es no site do [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 22:50:42","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2569"}],"collection":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2569"}],"version-history":[{"count":0,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2569\/revisions"}],"wp:attachment":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}