{"id":2707,"date":"2019-08-01T21:07:08","date_gmt":"2019-08-01T21:07:08","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2019\/08\/01\/i-semana-de-jogos-no-centro-de-atendimento-socioeducativo-de-criciuma\/"},"modified":"2019-08-01T21:07:08","modified_gmt":"2019-08-01T21:07:08","slug":"i-semana-de-jogos-no-centro-de-atendimento-socioeducativo-de-criciuma","status":"publish","type":"post","link":"https:\/\/sejuri.sc.gov.br\/en\/i-semana-de-jogos-no-centro-de-atendimento-socioeducativo-de-criciuma\/","title":{"rendered":"I\u00aa Semana de Jogos no Centro de Atendimento Socioeducativo de Crici\u00fama"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Na semana de 08 a 12 de julho foi realizada a I\u00aa Semana de Jogos e Gincana no CASE de Crici\u00fama, tendo como objetivo desenvolver a coopera\u00e7\u00e3o e a integra\u00e7\u00e3o entre os adolescentes e de todos os profissionais que comp\u00f5e a rotina di\u00e1ria da unidade.<\/p>\n<p style=\"text-align: justify;\">Foram realizadas diferentes atividades como: quiz \u2013 forma de jogo onde se questiona os participantes pontuando-os com suas respostas. A Atividade envolveu conte\u00fados de todas as disciplinas escolares, como salto em dist\u00e2ncia, arremesso, xadrez, corrida de 100 metros e teste de impuls\u00e3o. Sempre incentivando a participa\u00e7\u00e3o e a inclus\u00e3o de todos.<\/p>\n<p style=\"text-align: justify;\">Uma das atra\u00e7\u00f5es desse evento foi o xadrez gigante, que foi gentilmente emprestado pela Funda\u00e7\u00e3o de Esportes de Crici\u00fama.<\/p>\n<p style=\"text-align: justify;\">Todos os adolescentes participaram e no final foi servido um delicioso lanche t\u00edpico junino, como uma forma de encerramento da semana e in\u00edcio das f\u00e9rias letivas.<\/p>","protected":false},"excerpt":{"rendered":"<p>Na semana de 08 a 12 de julho foi realizada a I\u00aa Semana de Jogos e Gincana no CASE de Crici\u00fama, tendo como objetivo desenvolver a coopera\u00e7\u00e3o e a integra\u00e7\u00e3o entre os adolescentes e de todos os profissionais que comp\u00f5e a rotina di\u00e1ria da unidade. Foram realizadas diferentes atividades como: quiz \u2013 forma de jogo [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":294,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 23:58:00","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2707"}],"collection":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2707"}],"version-history":[{"count":0,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2707\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/294"}],"wp:attachment":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}