{"id":599,"date":"2021-04-19T11:41:56","date_gmt":"2021-04-19T11:41:56","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2021\/04\/19\/adolescentes-do-sistema-socioeducativo-catarinense-se-destacam-no-enem-ppl-2021-e-garantem-vagas-em-universidades-publicas\/"},"modified":"2021-04-19T11:41:56","modified_gmt":"2021-04-19T11:41:56","slug":"adolescentes-do-sistema-socioeducativo-catarinense-se-destacam-no-enem-ppl-2021-e-garantem-vagas-em-universidades-publicas","status":"publish","type":"post","link":"https:\/\/sejuri.sc.gov.br\/en\/adolescentes-do-sistema-socioeducativo-catarinense-se-destacam-no-enem-ppl-2021-e-garantem-vagas-em-universidades-publicas\/","title":{"rendered":"Adolescentes do sistema socioeducativo catarinense se destacam no ENEM PPL 2021 e concorrem a vagas em Universidades P\u00fablicas"},"content":{"rendered":"<p style=\"line-height: normal; text-align: justify; text-indent: 42.55pt;\">Nos dias 23 e 24 de fevereiro de 2021 foi realizado o Exame Nacional do Ensino M\u00e9dio para Pessoas Privadas de Liberdade\/ENEM PPL, nas Unidades Socioeducativas de todos os Estados brasileiros. Em Santa Catarina, 67 (sessenta e sete) adolescentes realizaram as provas; destes, 08 (oito) disputaram vagas para ingressar no Ensino Superior e os demais realizaram somente como treinamento.&nbsp;<\/p>\n<p style=\"line-height: normal; text-align: justify; text-indent: 42.55pt;\">&nbsp;O resultado do exame foi divulgado no dia 30 de mar\u00e7o de 2021. Dos 08 (oito) adolescentes que estavam concorrendo \u00e0s vagas, 02 (dois) obtiveram a m\u00e9dia necess\u00e1ria e puderam ser inscritos no SISU &#8211; Sistema \u00danico de Sele\u00e7\u00e3o Unificada, para concorrer a vagas para Universidades P\u00fablicas.<\/p>\n<p style=\"line-height: normal; text-align: justify; text-indent: 42.55pt;\">&nbsp;Um adolescente de 19 anos, do Casep de Joinville, teve uma pontua\u00e7\u00e3o em algumas \u00e1reas de ensino acima da m\u00e9dia nacional. Destaque para Ci\u00eancias da Natureza em que obteve 548,2 pontos, quando a m\u00e9dia nacional foi de 490,39. Na reda\u00e7\u00e3o com o tema &#8220;O desafio de reduzir as desigualdades entre as regi\u00f5es do Brasil&#8221;, o adolescente atingiu a pontua\u00e7\u00e3o 640.0, sendo a m\u00e9dia nacional de 620.0 pontos. Incentivado pelo grupo t\u00e9cnico da Unidade, ele se inscreveu no curso de Engenharia de Transporte e Log\u00edstica na Universidade Federal de Santa Catarina (UFSC) e no Curso de Licenciatura em Qu\u00edmica na Universidade do Estado de Santa Catarina (UDESC). Questionado sobre a oportunidade e os resultados obtidos, o adolescente demonstra estar feliz e orgulhoso de si mesmo por ter conseguido e reconhece o apoio recebido dos profissionais da Unidade.<\/p>\n<p style=\"line-height: normal; text-align: justify; text-indent: 42.55pt;\">&nbsp;\u00c9 importante observar que o desempenho dos demais adolescentes de Santa Catarina que participaram do ENEM\/PPL foi significativo, pois mesmo n\u00e3o obtendo a pontua\u00e7\u00e3o necess\u00e1ria para concorrer a vagas para o Ensino Superior surpreenderam positivamente com os resultados conseguidos em determinadas disciplinas. &nbsp;<\/p>\n<p style=\"line-height: normal; text-align: justify; text-indent: 42.55pt;\">&nbsp;Resultados como estes fortificam o processo da Socioeduca\u00e7\u00e3o, garantindo a ressignifica\u00e7\u00e3o de valores e condutas destes adolescentes e contribuindo para o afastamento da pr\u00e1tica infracional.<\/p><\/p>","protected":false},"excerpt":{"rendered":"<p>Nos dias 23 e 24 de fevereiro de 2021 foi realizado o Exame Nacional do Ensino M\u00e9dio para Pessoas Privadas de Liberdade\/ENEM PPL, nas Unidades Socioeducativas de todos os Estados brasileiros. Em Santa Catarina, 67 (sessenta e sete) adolescentes realizaram as provas; destes, 08 (oito) disputaram vagas para ingressar no Ensino Superior e os demais [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":598,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:05:16","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/599"}],"collection":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=599"}],"version-history":[{"count":0,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/599\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}