{"id":669,"date":"2021-07-29T16:10:24","date_gmt":"2021-07-29T16:10:24","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2021\/07\/29\/curiosidades-sobre-as-olimpiadas-de-toquio-no-casep-de-cacador\/"},"modified":"2021-07-29T16:10:24","modified_gmt":"2021-07-29T16:10:24","slug":"curiosidades-sobre-as-olimpiadas-de-toquio-no-casep-de-cacador","status":"publish","type":"post","link":"https:\/\/sejuri.sc.gov.br\/en\/curiosidades-sobre-as-olimpiadas-de-toquio-no-casep-de-cacador\/","title":{"rendered":"CURIOSIDADES SOBRE AS OLIMP\u00cdADAS DE T\u00d3QUIO NO CASEP DE CA\u00c7ADOR"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong><\/strong>As modalidades esportivas das Ol\u00edmpiadas de T\u00f3quio 2021 depertou a curiosidade dos adolescentes do Casep de Ca\u00e7ador. Os instrutores do projeto Movimente-se e do projeto Criarte realizaram uma oficina sobre as olimp\u00edadas para tirar todas as d\u00favidas dos socioeducandos.&nbsp;<\/p>\n<p style=\"text-align: justify;\">Foram abordados temas como a hist\u00f3ria das jogos ol\u00edmpicos, modalidades esportivas, quadro de medalhas, pa\u00edses participantes, curiosidades, mascotes, tocha e significado da bandeira ol\u00edmpica (an\u00e9is ol\u00edmpicos).&nbsp;<\/p>\n<p style=\"text-align: justify;\">Os socioeducandos desenharam o s\u00edmbolo ol\u00edmpico e algumas bandeiras de pa\u00edses participantes das ol\u00edmpiadas.&nbsp;<\/p>\n<p style=\"text-align: justify;\">A oficina teve como objetivo incentivar os adolescentes a praticar esportes e, ao mesmo tempo, tirar as d\u00favidas sobre esse evento esportivo e suas modalidades que, muitas vezes, n\u00e3o temos acesso e nem&nbsp; conhecimento que existam.&nbsp;<\/p>\n<p style=\"text-align: justify;\">Os Jogos Ol\u00edmpicos s\u00e3o importantes, principalmente, por despertarem o interesse da popula\u00e7\u00e3o pelas pr\u00e1ticas esportivas. O h\u00e1bito de praticar um esporte com regularidade traz in\u00fameros benef\u00edcios tanto para o corpo quanto para a mente.&nbsp;<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m disso, passa uma mensagem de uni\u00e3o entre as na\u00e7\u00f5es. Mesmo que elas compitam entre si, h\u00e1 um esp\u00edrito de fraternidade entre os atletas.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>As modalidades esportivas das Ol\u00edmpiadas de T\u00f3quio 2021 depertou a curiosidade dos adolescentes do Casep de Ca\u00e7ador. Os instrutores do projeto Movimente-se e do projeto Criarte realizaram uma oficina sobre as olimp\u00edadas para tirar todas as d\u00favidas dos socioeducandos.&nbsp; Foram abordados temas como a hist\u00f3ria das jogos ol\u00edmpicos, modalidades esportivas, quadro de medalhas, pa\u00edses participantes, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":668,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 00:53:16","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/669"}],"collection":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=669"}],"version-history":[{"count":0,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/669\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/668"}],"wp:attachment":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}