{"id":893,"date":"2022-12-06T17:40:55","date_gmt":"2022-12-06T17:40:55","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2022\/12\/06\/pela-primeira-vez-o-departamento-de-administracao-socioeducativa-participa-de-desfiles-civicos\/"},"modified":"2022-12-06T17:40:55","modified_gmt":"2022-12-06T17:40:55","slug":"pela-primeira-vez-o-departamento-de-administracao-socioeducativa-participa-de-desfiles-civicos","status":"publish","type":"post","link":"https:\/\/sejuri.sc.gov.br\/en\/pela-primeira-vez-o-departamento-de-administracao-socioeducativa-participa-de-desfiles-civicos\/","title":{"rendered":"Pela primeira vez o Departamento de Administra\u00e7\u00e3o Socioeducativa participa de desfiles c\u00edvicos"},"content":{"rendered":"<p style=\"text-align: justify;\">O Dease &#8211; Departamento de Administra\u00e7\u00e3o Socioeducativa \u00e9 um \u00f3rg\u00e3o da Secretaria de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa respons\u00e1vel pela cust\u00f3dia dos adolescentes em conflito com a lei em cumprimento de medida socioeducativa de interna\u00e7\u00e3o e de semiliberdade. As medidas socioeducativas t\u00eam por finalidade a educa\u00e7\u00e3o, restaura\u00e7\u00e3o, socializa\u00e7\u00e3o e a integra\u00e7\u00e3o do indiv\u00edduo no conv\u00edvio social.<\/p>\n<p style=\"text-align: justify;\">Ao todo, o Estado possui 24 Unidades que atendem adolescentes dos 12 aos 18 anos que praticam ato infracional, podendo estender, excepcionalmente, at\u00e9 os 21 anos de idade.<\/p>\n<p style=\"text-align: justify;\">O Dease tamb\u00e9m conta com outros setores de apoio: Grupos de Apoio e Escolta Socioeducativa, Grupos de Opera\u00e7\u00e3o com C\u00e3es, N\u00facleo de Seguran\u00e7a Institucional, N\u00facleos de Intelig\u00eancia e N\u00facleo de Interven\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m de manter a ordem e a disciplina nas Unidades Socioeducativas os servidores do Dease atuam na socioeduca\u00e7\u00e3o, na perspectiva de despertar a reabilita\u00e7\u00e3o social dos internos, proporcionando alternativas para o resgate de sua cidadania.<\/p>\n<p style=\"text-align: justify;\">No m\u00eas de agosto, o Dease participou do desfile c\u00edvico em comemora\u00e7\u00e3o ao 105\u00ba anivers\u00e1rio do munic\u00edpio de Chapec\u00f3, juntamente com outros \u00f3rg\u00e3os de seguran\u00e7a e entidades convidadas, bem como participou de desfiles em datas comemorativas, em outros munic\u00edpios.<\/p>\n<\/p>\n<p style=\"text-align: justify;\">Ainda, pela primeira vez, o Dease participou do desfile c\u00edvico-militar na capital catarinense e outras cidades de Santa Catarina, no dia 07 de setembro, data comemorativa do Bicenten\u00e1rio da Independ\u00eancia do Brasil.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-892\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2022\/12\/Desfile_civico_1-715.jpg\" alt=\"Desfile c\u00edvico 1\" width=\"498\" height=\"336\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>O Dease &#8211; Departamento de Administra\u00e7\u00e3o Socioeducativa \u00e9 um \u00f3rg\u00e3o da Secretaria de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa respons\u00e1vel pela cust\u00f3dia dos adolescentes em conflito com a lei em cumprimento de medida socioeducativa de interna\u00e7\u00e3o e de semiliberdade. As medidas socioeducativas t\u00eam por finalidade a educa\u00e7\u00e3o, restaura\u00e7\u00e3o, socializa\u00e7\u00e3o e a integra\u00e7\u00e3o do indiv\u00edduo no [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 23:01:39","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/893"}],"collection":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=893"}],"version-history":[{"count":0,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/893\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}