{"id":967,"date":"2023-01-26T21:42:17","date_gmt":"2023-01-26T21:42:17","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2023\/01\/26\/formatura-do-programa-e-iniciacao-do-trabalho-no-casep-de-cacador\/"},"modified":"2023-01-26T21:42:17","modified_gmt":"2023-01-26T21:42:17","slug":"formatura-do-programa-e-iniciacao-do-trabalho-no-casep-de-cacador","status":"publish","type":"post","link":"https:\/\/sejuri.sc.gov.br\/en\/formatura-do-programa-e-iniciacao-do-trabalho-no-casep-de-cacador\/","title":{"rendered":"Formatura do Programa e Inicia\u00e7\u00e3o do Trabalho no CASEP de Ca\u00e7ador"},"content":{"rendered":"<\/p>\n<p style=\"text-align: justify;\">O CASEP de Ca\u00e7ador, em parceria com o CIEE \u2013 Centro de Integra\u00e7\u00e3o Empresa-Escola promoveu, no final do m\u00eas de dezembro de 2022, a formatura do Programa e Inicia\u00e7\u00e3o do Trabalho (PIT), dos socioeducandos que conclu\u00edram os m\u00f3dulos na Unidade:<\/p>\n<p style=\"text-align: justify;\">&#8211; Avalia\u00e7\u00e3o coletiva, perspectivas e novos passos;<\/p>\n<p style=\"text-align: justify;\">&#8211; Criatividade e inova\u00e7\u00e3o;<\/p>\n<p style=\"text-align: justify;\">&#8211; Din\u00e2micas de grupo;<\/p>\n<p style=\"text-align: justify;\">&#8211; Entrevista tradicional e Entrevista virtual;<\/p>\n<p style=\"text-align: justify;\">&#8211; Eu no mundo do trabalho;<\/p>\n<p style=\"text-align: justify;\">&#8211; Intelig\u00eancia emocional no trabalho;<\/p>\n<p style=\"text-align: justify;\">&#8211; Juventude e trabalho;<\/p>\n<p style=\"text-align: justify;\">&#8211; Planejamento de carreira;<\/p>\n<p style=\"text-align: justify;\">&#8211; Redes sociais para curr\u00edculo tradicional e v\u00eddeo curr\u00edculo;<\/p>\n<p style=\"text-align: justify;\">&#8211; Roda das profiss\u00f5es.<\/p>\n<p style=\"text-align: justify;\">Os adolescentes foram orientados e motivados a concluir o programa de forma interativa e segura, buscando novos prop\u00f3sitos pessoais e profissionais.<\/p>\n<p style=\"text-align: justify;\">A oferta de cursos e oficinas tem como objetivo a qualifica\u00e7\u00e3o e capacita\u00e7\u00e3o dos adolescentes para a inser\u00e7\u00e3o no mercado de trabalho quando findarem o cumprimento da medida socioeducativa.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-965\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2023\/01\/Formatura_-480.jpeg\" alt=\"Formatura \" width=\"500\" height=\"375\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-966\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2023\/01\/Formatura_1-5ba.jpeg\" alt=\"Formatura 1\" width=\"500\" height=\"375\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>O CASEP de Ca\u00e7ador, em parceria com o CIEE \u2013 Centro de Integra\u00e7\u00e3o Empresa-Escola promoveu, no final do m\u00eas de dezembro de 2022, a formatura do Programa e Inicia\u00e7\u00e3o do Trabalho (PIT), dos socioeducandos que conclu\u00edram os m\u00f3dulos na Unidade: &#8211; Avalia\u00e7\u00e3o coletiva, perspectivas e novos passos; &#8211; Criatividade e inova\u00e7\u00e3o; &#8211; Din\u00e2micas de grupo; [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":964,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 22:47:24","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/967"}],"collection":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=967"}],"version-history":[{"count":0,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}