{"id":970,"date":"2023-01-31T16:43:25","date_gmt":"2023-01-31T16:43:25","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2023\/01\/31\/janeiro-branco-saude-mental-e-tema-de-atividades-na-semiliberdade-de-blumenau-e-casep-de-sao-jose-do-cedro\/"},"modified":"2023-01-31T16:43:25","modified_gmt":"2023-01-31T16:43:25","slug":"janeiro-branco-saude-mental-e-tema-de-atividades-na-semiliberdade-de-blumenau-e-casep-de-sao-jose-do-cedro","status":"publish","type":"post","link":"https:\/\/sejuri.sc.gov.br\/en\/janeiro-branco-saude-mental-e-tema-de-atividades-na-semiliberdade-de-blumenau-e-casep-de-sao-jose-do-cedro\/","title":{"rendered":"JANEIRO BRANCO \u2013 Sa\u00fade Mental \u00e9 tema de atividades na Semiliberdade de Blumenau e Casep de S\u00e3o Jos\u00e9 do Cedro"},"content":{"rendered":"<p style=\"text-align: justify;\">A campanha &#8220;Janeiro Branco&#8221; \u00e9 um movimento dedicado a convidar as pessoas a pensarem sobre o sentido e o prop\u00f3sito das suas vidas, a qualidade dos seus relacionamentos e o quanto elas conhecem sobre si mesmas, suas emo\u00e7\u00f5es, seus pensamentos e sobre os seus comportamentos.&nbsp; Seu objetivo \u00e9 chamar a aten\u00e7\u00e3o dos indiv\u00edduos, das institui\u00e7\u00f5es, das sociedades e das autoridades para as necessidades relacionadas \u00e0 Sa\u00fade Mental.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>OFICINA \u201cJANEIRO BRANCO\u201d NA SEMILIBERDADE DE BLUMENAU<\/strong><\/p>\n<p style=\"text-align: justify;\">Os socioeducandos da Semiliberdade de Blumenau participaram de oficina sobre a campanha \u201cJaneiro Branco\u201d. Na atividade os jovens assistiram v\u00eddeos de conscientiza\u00e7\u00e3o e participaram de uma atividade escrita, que teve o objetivo de ressaltar a import\u00e2ncia do cuidado com a sa\u00fade mental, focando no equil\u00edbrio e na paz interior.<\/p>\n<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong>PALESTRA SOBRE A SA\u00daDE MENTAL NO CASEP DE S\u00c3O JOS\u00c9 DO CEDRO<\/strong><\/p>\n<p style=\"text-align: justify;\">No Casep de S\u00e3o Jos\u00e9 do Cedro os socioeducandos participaram de uma palestra sobre a campanha \u201cJaneiro Branco\u201d, sendo orientados sobre a import\u00e2ncia do di\u00e1logo e conhecimento da dimens\u00e3o e gravidade quando nos descuidamos da sa\u00fade mental.<\/p>\n<p style=\"text-align: justify;\">Falar contribui para dar visibilidade ao contexto do cuidado em sa\u00fade mental, pois potencializa o acolhimento por parte dos gestores, dos profissionais de sa\u00fade, redes de apoio, familiares e da comunidade em que estamos inseridos.<\/p>\n<p style=\"text-align: justify;\">Durante a palestra, ressaltou-se que n\u00e3o existe uma forma \u00fanica de adoecimento mental. Por isso, para manter a sa\u00fade mental em dia, algumas dicas s\u00e3o valiosas como a pr\u00e1tica de atividades f\u00edsicas, manter uma alimenta\u00e7\u00e3o saud\u00e1vel, se hidratar, manter um sono de qualidade, cuidar bem dos relacionamentos, se valorizar e estar em companhia de pessoas otimistas.<\/p>\n<p style=\"text-align: justify;\">O prop\u00f3sito \u00e9 alertar aos jovens sobre a preven\u00e7\u00e3o das doen\u00e7as decorrentes do estresse, incluindo os transtornos mentais mais comuns como depress\u00e3o, ansiedade e p\u00e2nico, ressaltando a import\u00e2ncia das pessoas que apresentam e percebem os sintomas n\u00e3o esperem por melhora sem a orienta\u00e7\u00e3o de um profissional de sa\u00fade.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-969\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2023\/01\/Janeiro_Branco_SJC_2023-3f4.png\" alt=\"Janeiro Branco SJC 2023\" width=\"590\" height=\"461\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>A campanha &#8220;Janeiro Branco&#8221; \u00e9 um movimento dedicado a convidar as pessoas a pensarem sobre o sentido e o prop\u00f3sito das suas vidas, a qualidade dos seus relacionamentos e o quanto elas conhecem sobre si mesmas, suas emo\u00e7\u00f5es, seus pensamentos e sobre os seus comportamentos.&nbsp; Seu objetivo \u00e9 chamar a aten\u00e7\u00e3o dos indiv\u00edduos, das institui\u00e7\u00f5es, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":968,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 22:55:59","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/970"}],"collection":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=970"}],"version-history":[{"count":0,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/970\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sejuri.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}